{"id":53,"count":2,"description":"","link":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/","name":"Yema","slug":"yema","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yema archivos - Alimentari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yema archivos - Alimentari\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/\" \/>\n<meta property=\"og:site_name\" content=\"Alimentari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/categoria-producto\\\/yema\\\/\",\"url\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/categoria-producto\\\/yema\\\/\",\"name\":\"Yema archivos - Alimentari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/categoria-producto\\\/yema\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/categoria-producto\\\/yema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/#website\",\"url\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/\",\"name\":\"Alimentari\",\"description\":\"Alimentari Chile\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/#organization\",\"name\":\"Alimentari\",\"url\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/alimentariLogo.svg\",\"contentUrl\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/alimentariLogo.svg\",\"caption\":\"Alimentari\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentarichile.cl\\\/web\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yema archivos - Alimentari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/","og_locale":"es_ES","og_type":"article","og_title":"Yema archivos - Alimentari","og_url":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/","og_site_name":"Alimentari","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/","url":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/","name":"Yema archivos - Alimentari","isPartOf":{"@id":"https:\/\/www.alimentarichile.cl\/web\/#website"},"breadcrumb":{"@id":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alimentarichile.cl\/web\/categoria-producto\/yema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.alimentarichile.cl\/web\/"},{"@type":"ListItem","position":2,"name":"Yema"}]},{"@type":"WebSite","@id":"https:\/\/www.alimentarichile.cl\/web\/#website","url":"https:\/\/www.alimentarichile.cl\/web\/","name":"Alimentari","description":"Alimentari Chile","publisher":{"@id":"https:\/\/www.alimentarichile.cl\/web\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alimentarichile.cl\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alimentarichile.cl\/web\/#organization","name":"Alimentari","url":"https:\/\/www.alimentarichile.cl\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alimentarichile.cl\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.alimentarichile.cl\/web\/wp-content\/uploads\/2026\/07\/alimentariLogo.svg","contentUrl":"https:\/\/www.alimentarichile.cl\/web\/wp-content\/uploads\/2026\/07\/alimentariLogo.svg","caption":"Alimentari"},"image":{"@id":"https:\/\/www.alimentarichile.cl\/web\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.alimentarichile.cl\/web\/wp-json\/wp\/v2\/product_cat\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alimentarichile.cl\/web\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.alimentarichile.cl\/web\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.alimentarichile.cl\/web\/wp-json\/wp\/v2\/product?product_cat=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}